{"id":13067,"date":"2018-04-20T00:00:00","date_gmt":"2018-04-20T03:00:00","guid":{"rendered":"http:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/"},"modified":"2021-11-25T15:27:06","modified_gmt":"2021-11-25T18:27:06","slug":"sites-para-contadores","status":"publish","type":"post","link":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/","title":{"rendered":"6 sites e portais que todo contador deve conhecer"},"content":{"rendered":"<p>A profiss\u00e3o de contador passou por grandes mudan\u00e7as nos \u00faltimos anos no Brasil, e essa transforma\u00e7\u00e3o \u00e9 vista de forma positiva. Os <strong><a href=\"http:\/\/portal.blbbrasilescoladenegocios.com.br\/profissionalizacao-em-contabilidade\/\" target=\"_blank\" rel=\"noopener\" class=\"broken_link\">contadores<\/a><\/strong> precisam reciclar seus conhecimentos com frequ\u00eancia, pois s\u00f3 assim conseguem <strong>manter uma boa coloca\u00e7\u00e3o no mercado perante a concorr\u00eancia<\/strong>.<\/p>\n<p>Atualiza\u00e7\u00e3o \u00e9 fundamental para o profissional que pretende alcan\u00e7ar uma posi\u00e7\u00e3o de responsabilidade no meio corporativo, que a cada dia \u00e9 mais disputado e requer conhecimentos espec\u00edficos sobre a contabilidade brasileira. Os profissionais que buscam ir al\u00e9m do que \u00e9 ensinado nos cursos universit\u00e1rios mostram seu interesse pela profiss\u00e3o e conseguem alcan\u00e7ar <strong>novas oportunidades na carreira<\/strong>.<\/p>\n<p>Neste post, voc\u00ea vai saber quais s\u00e3o os seis melhores sites para contadores acompanharem, al\u00e9m de conhecer um pouco mais sobre a vis\u00e3o do mercado da contabilidade apresentada&nbsp;nesses portais. Acompanhe o texto!<\/p>\n<h2><strong>Os melhores portais de not\u00edcias da \u00e1rea cont\u00e1bil<\/strong><\/h2>\n<p>Acompanhar as novidades da \u00e1rea cont\u00e1bil por meio de ve\u00edculos de comunica\u00e7\u00e3o especializados \u00e9 importante para o bom andamento do trabalho&nbsp;no dia a dia&nbsp;e para trocar informa\u00e7\u00f5es com gestores durante o expediente \u2014 o <strong>networking<\/strong> tamb\u00e9m \u00e9 uma ferramenta poderosa para o profissional que deseja alcan\u00e7ar objetivos concretos na carreira.<\/p>\n<p>Sendo assim, listamos, a seguir, alguns dos principais meios de comunica\u00e7\u00e3o no ramo empresarial, cont\u00e1bil e <strong><a href=\"http:\/\/portal.blbbrasilescoladenegocios.com.br\/crime-tributario\/\" target=\"_blank\" rel=\"noopener\" class=\"broken_link\">tribut\u00e1rio<\/a><\/strong>.<\/p>\n<h3><strong>1. Conselho Federal de Contabilidade (CFC)<\/strong><\/h3>\n<p>O site do <strong><a href=\"http:\/\/cfc.org.br\/noticias\/\" target=\"_blank\" rel=\"noopener\">CFC<\/a><\/strong> re\u00fane as principais not\u00edcias do universo cont\u00e1bil. A institui\u00e7\u00e3o \u00e9 uma autarquia especial corporativa, que comunica os contadores sobre palestras, eventos e conta com uma ag\u00eancia de not\u00edcias com informativos sobre as principais <strong>atualiza\u00e7\u00f5es do setor de contabilidade<\/strong>.<\/p>\n<p>O CFC tem uma vis\u00e3o de mercado atual e disponibiliza em seu site informa\u00e7\u00f5es \u00fateis, que ajudam o contador em uma atualiza\u00e7\u00e3o r\u00e1pida. Al\u00e9m disso, ele \u00e9 importante pelas palestras disponibilizadas virtualmente, que ajudam na forma\u00e7\u00e3o de um contador,&nbsp;e por abordarem temas com informa\u00e7\u00f5es relevantes. \u00c9 um site confi\u00e1vel e de autoridade na \u00e1rea cont\u00e1bil.<\/p>\n<h3><strong>2. Instituto dos Auditores Independentes do Brasil (Ibracon)<\/strong><\/h3>\n<p>Esse instituto foi criado em 1971, com o objetivo de unir duas empresas de contadores que, na \u00e9poca, trabalhavam de forma independente, o Instituto dos Contadores P\u00fablicos do Brasil (ICPB) e o Instituto Brasileiro de Auditores Independentes (IBAI).<\/p>\n<p>O portal do <strong><a href=\"http:\/\/www.ibracon.com.br\/ibracon\/Portugues\/index.php\" target=\"_blank\" rel=\"noopener\" class=\"broken_link\">Ibracon<\/a><\/strong> \u00e9 um meio de informa\u00e7\u00e3o atual e bem organizado, voltado para profissionais que buscam not\u00edcias r\u00e1pidas e que auxiliam na forma\u00e7\u00e3o profissional. O site ainda disponibiliza para os associados a Revista Transpar\u00eancia, que \u00e9 uma exclusividade do instituto.<\/p>\n<h3><strong>3. Cont\u00e1beis: o portal da profiss\u00e3o cont\u00e1bil<\/strong><\/h3>\n<p>Criado em 1999, o site <strong><a href=\"http:\/\/www.contabeis.com.br\/artigos\/\" target=\"_blank\" rel=\"noopener\">Cont\u00e1beis<\/a><\/strong> re\u00fane as principais not\u00edcias do setor tribut\u00e1rio, econ\u00f4mico e empresarial (que engloba tamb\u00e9m a contabilidade). Tem uma ferramenta interessante que \u00e9 o <strong>f\u00f3rum de debates para contadores<\/strong>, no qual os profissionais podem criar networking e conversar sobre os principais assuntos da \u00e1rea \u2014 esse espa\u00e7o virtual \u00e9 considerado um dos melhores f\u00f3runs do setor.<\/p>\n<p>O portal tamb\u00e9m disponibiliza assuntos important\u00edssimos sobre o universo cont\u00e1bil, o que o torna uma \u00f3tima fonte de not\u00edcias para consultas r\u00e1pidas e di\u00e1rias.<\/p>\n<h3><strong>4. Portal da Classe Cont\u00e1bil<\/strong><\/h3>\n<p>No ar h\u00e1 mais de uma d\u00e9cada, o <strong><a href=\"http:\/\/www.classecontabil.com.br\/\" target=\"_blank\" rel=\"noopener\" class=\"broken_link\">Portal da Classe Cont\u00e1bil<\/a><\/strong> \u00e9 conhecido como <strong>uma das melhores fontes de informa\u00e7\u00e3o<\/strong> sobre o universo da contabilidade no Brasil.<\/p>\n<p>Os moderadores da p\u00e1gina cedem espa\u00e7o para publica\u00e7\u00e3o de artigos que abordam assuntos relacionados \u00e0 \u00e1rea e oferecem a chance para contadores se candidatarem e terem a oportunidade de trabalhar como consultores no pr\u00f3prio portal.<\/p>\n<p>Os cursos e artigos que o Portal da Classe Cont\u00e1bil disponibiliza ajudam na atualiza\u00e7\u00e3o profissional, trazendo clareza nas informa\u00e7\u00f5es e eliminando d\u00favidas recorrentes relacionadas ao dia a dia de trabalho e ao ambiente corporativo.<\/p>\n<h3><strong>5. Conselhos Regionais de Contabilidade<\/strong><\/h3>\n<p>O Conselho Regional de Contabilidade foi criado com o intuito de <strong>regulamentar a profiss\u00e3o de contador<\/strong>. Com sede em Bras\u00edlia e presente em todos os estados da federa\u00e7\u00e3o, como o&nbsp;<a href=\"https:\/\/online.crcsp.org.br\/portal\/index.asp\" target=\"_blank\" rel=\"noopener\"><strong>CRC SP<\/strong><\/a> para contadores do estado de S\u00e3o Paulo, fiscaliza e desenvolve atividades para a valoriza\u00e7\u00e3o da profiss\u00e3o cont\u00e1bil.<\/p>\n<p>O CRC do seu estado&nbsp;promove o cronograma de atividades e educa\u00e7\u00e3o continuada para a classe cont\u00e1bil&nbsp;em parcerias com institui\u00e7\u00f5es de ensino, proporcionando descontos em universidades que oferecem cursos de contabilidade (gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o, por exemplo).<\/p>\n<p>Portanto, \u00e9 uma \u00f3tima op\u00e7\u00e3o de consulta para voc\u00ea se manter atualizado diariamente nos assuntos pertinentes ao ramo cont\u00e1bil e fazer networking, j\u00e1 que o CRC faz conven\u00e7\u00f5es regionais e estaduais para promover o encontro de profissionais da \u00e1rea.<\/p>\n<h3><strong>6. Comit\u00ea de Pronunciamento Cont\u00e1bil<\/strong><\/h3>\n<p>O&nbsp;Comit\u00ea de Pronunciamentos Cont\u00e1beis (<strong><a href=\"http:\/\/www.cpc.org.br\/CPC\" target=\"_blank\" rel=\"noopener\">CPC<\/a><\/strong>)&nbsp;\u00e9 uma entidade aut\u00f4noma que disponibiliza not\u00edcias para o profissional acompanhar a evolu\u00e7\u00e3o das normas internacionais de contabilidade.<\/p>\n<p>O site funciona como uma forma de uni\u00e3o de diversas entidades, com o objetivo de <strong>suprir as necessidades de converg\u00eancia internacional das normas cont\u00e1beis<\/strong>, <strong>centralizar a emiss\u00e3o das normas da contabilidade no Brasil<\/strong> e representar o processo democr\u00e1tico na produ\u00e7\u00e3o de informa\u00e7\u00f5es do setor cont\u00e1bil.<\/p>\n<p>Assim sendo, \u00e9 uma fonte de informa\u00e7\u00f5es sobre os pronunciamentos t\u00e9cnicos, orienta\u00e7\u00f5es e interpreta\u00e7\u00f5es das normas internacionais do setor.<\/p>\n<h2><strong>A import\u00e2ncia dos sites para contadores<\/strong><\/h2>\n<p>A profiss\u00e3o de contador tem como natureza o desafio. Afinal, trabalhar com a parte financeira e pessoal de uma empresa \u00e9 sempre uma tarefa de alta responsabilidade e que exige um <strong>alto n\u00edvel de conhecimento e clareza na an\u00e1lise de dados<\/strong>.<\/p>\n<p>Estar atualizado com as legisla\u00e7\u00f5es e novidades do setor cont\u00e1bil \u00e9 essencial para o bom desempenho&nbsp;da atividade e traz benef\u00edcios para a carreira, afinal, conhecimento \u00e9 sempre bem-vindo e faz uma grande diferen\u00e7a na troca de informa\u00e7\u00f5es com os colegas de profiss\u00e3o.<\/p>\n<p>Sendo assim, ter boas alternativas de comunica\u00e7\u00e3o, como as op\u00e7\u00f5es que listamos neste post, s\u00e3o fundamentais para o profissional.&nbsp;Ao acompanhar fontes de not\u00edcias sobre o setor em que trabalha, voc\u00ea ter\u00e1 melhores dados\/informa\u00e7\u00f5es para levar em reuni\u00f5es com gestores, conversar com os colegas de profiss\u00e3o e tamb\u00e9m para avaliar o pr\u00f3prio desempenho como profissional.<\/p>\n<p>Os portais que sugerimos aqui s\u00e3o apenas seis das muitas op\u00e7\u00f5es de sites para contadores que existem na Internet atualmente. Pesquise por boas refer\u00eancias, pe\u00e7a a opini\u00e3o de outros profissionais e mantenha-se sempre focado em oportunidades de desenvolvimento de carreira.<\/p>\n<p>Esperamos que voc\u00ea tenha gostado das dicas e que essas sugest\u00f5es possam ser realmente \u00fateis para o seu trabalho. Se voc\u00ea gostou do texto, o que acha de compartilh\u00e1-lo em suas redes sociais? At\u00e9 o pr\u00f3ximo post!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A profiss\u00e3o de contador passou por grandes mudan\u00e7as nos \u00faltimos anos no Brasil, e essa transforma\u00e7\u00e3o \u00e9 vista de forma positiva. Os contadores precisam reciclar seus conhecimentos com frequ\u00eancia, pois s\u00f3 assim conseguem manter uma boa coloca\u00e7\u00e3o no mercado perante a concorr\u00eancia.<\/p>\n","protected":false},"author":3,"featured_media":13077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"spay_email":""},"categories":[2,39,40,705,63],"tags":[11,3,794,795,796],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>6 sites e portais que todo contador deve conhecer<\/title>\n<meta name=\"description\" content=\"Confira uma lista com seis sites e portais que todo contador e demais profissionais da \u00e1rea da Contabilidade devem conhecer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 sites e portais que todo contador deve conhecer\" \/>\n<meta property=\"og:description\" content=\"Confira uma lista com seis sites e portais que todo contador e demais profissionais da \u00e1rea da Contabilidade devem conhecer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/\" \/>\n<meta property=\"og:site_name\" content=\"BLB Blog\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-20T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-25T18:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.blbbrasil.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg?fit=840%2C522&#038;ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Grupo BLB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/#website\",\"url\":\"https:\/\/blbescoladenegocios.com.br\/blog\/\",\"name\":\"BLB Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blbescoladenegocios.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/i0.wp.com\/blbescoladenegocios.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg?fit=840%2C522&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/blbescoladenegocios.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg?fit=840%2C522&ssl=1\",\"width\":840,\"height\":522,\"caption\":\"6 portais e sites para contadores\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#webpage\",\"url\":\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/\",\"name\":\"6 sites e portais que todo contador deve conhecer\",\"isPartOf\":{\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#primaryimage\"},\"datePublished\":\"2018-04-20T03:00:00+00:00\",\"dateModified\":\"2021-11-25T18:27:06+00:00\",\"author\":{\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/#\/schema\/person\/0f726650fc88a2b0090b93d83ef26b6a\"},\"description\":\"Confira uma lista com seis sites e portais que todo contador e demais profissionais da \\u00e1rea da Contabilidade devem conhecer.\",\"breadcrumb\":{\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/blbescoladenegocios.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"6 sites e portais que todo contador deve conhecer\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/#\/schema\/person\/0f726650fc88a2b0090b93d83ef26b6a\",\"name\":\"Grupo BLB\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/blbescoladenegocios.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c39324242025e13ddf769a9fc2b6bb94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c39324242025e13ddf769a9fc2b6bb94?s=96&d=mm&r=g\",\"caption\":\"Grupo BLB\"},\"url\":\"https:\/\/blbescoladenegocios.com.br\/blog\/author\/blbbr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 sites e portais que todo contador deve conhecer","description":"Confira uma lista com seis sites e portais que todo contador e demais profissionais da \u00e1rea da Contabilidade devem conhecer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/","og_locale":"pt_BR","og_type":"article","og_title":"6 sites e portais que todo contador deve conhecer","og_description":"Confira uma lista com seis sites e portais que todo contador e demais profissionais da \u00e1rea da Contabilidade devem conhecer.","og_url":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/","og_site_name":"BLB Blog","article_published_time":"2018-04-20T03:00:00+00:00","article_modified_time":"2021-11-25T18:27:06+00:00","og_image":[{"width":840,"height":522,"url":"https:\/\/i0.wp.com\/www.blbbrasil.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg?fit=840%2C522&ssl=1","path":"\/srv\/www\/htdocs\/blbbrasil.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg","size":"full","id":13077,"alt":"6 portais e sites para contadores","pixels":438480,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Grupo BLB","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/blbescoladenegocios.com.br\/blog\/#website","url":"https:\/\/blbescoladenegocios.com.br\/blog\/","name":"BLB Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blbescoladenegocios.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/i0.wp.com\/blbescoladenegocios.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg?fit=840%2C522&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blbescoladenegocios.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg?fit=840%2C522&ssl=1","width":840,"height":522,"caption":"6 portais e sites para contadores"},{"@type":"WebPage","@id":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#webpage","url":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/","name":"6 sites e portais que todo contador deve conhecer","isPartOf":{"@id":"https:\/\/blbescoladenegocios.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#primaryimage"},"datePublished":"2018-04-20T03:00:00+00:00","dateModified":"2021-11-25T18:27:06+00:00","author":{"@id":"https:\/\/blbescoladenegocios.com.br\/blog\/#\/schema\/person\/0f726650fc88a2b0090b93d83ef26b6a"},"description":"Confira uma lista com seis sites e portais que todo contador e demais profissionais da \u00e1rea da Contabilidade devem conhecer.","breadcrumb":{"@id":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blbescoladenegocios.com.br\/blog\/sites-para-contadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blbescoladenegocios.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"6 sites e portais que todo contador deve conhecer"}]},{"@type":"Person","@id":"https:\/\/blbescoladenegocios.com.br\/blog\/#\/schema\/person\/0f726650fc88a2b0090b93d83ef26b6a","name":"Grupo BLB","image":{"@type":"ImageObject","@id":"https:\/\/blbescoladenegocios.com.br\/blog\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/c39324242025e13ddf769a9fc2b6bb94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c39324242025e13ddf769a9fc2b6bb94?s=96&d=mm&r=g","caption":"Grupo BLB"},"url":"https:\/\/blbescoladenegocios.com.br\/blog\/author\/blbbr\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blbescoladenegocios.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg?fit=840%2C522&ssl=1","fimg_url":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-content\/uploads\/2018\/06\/sites-para-contadores.jpg","_links":{"self":[{"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/posts\/13067"}],"collection":[{"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/comments?post=13067"}],"version-history":[{"count":3,"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/posts\/13067\/revisions"}],"predecessor-version":[{"id":20157,"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/posts\/13067\/revisions\/20157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/media\/13077"}],"wp:attachment":[{"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/media?parent=13067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/categories?post=13067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blbescoladenegocios.com.br\/blog\/wp-json\/wp\/v2\/tags?post=13067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}